{"id":849,"date":"2015-06-22T11:06:51","date_gmt":"2015-06-22T11:06:51","guid":{"rendered":"http:\/\/etruscanvirtualexperience.cineca.it\/?p=849"},"modified":"2022-03-29T11:57:45","modified_gmt":"2022-03-29T09:57:45","slug":"infografica-di-ati-alla-scoperta-di-veio","status":"publish","type":"post","link":"https:\/\/visitlab.cineca.it\/index.php\/2015\/06\/22\/infografica-di-ati-alla-scoperta-di-veio\/","title":{"rendered":"Infografica di &#8220;Ati alla scoperta di Veio&#8221;"},"content":{"rendered":"<p>Che Ati fosse un fiore gi\u00e0 lo sapevamo; adesso, grazie all&#8217;infografica realizzata da Daniele, ne abbiamo la certezza.<br \/>\nL&#8217;<strong>infografica<\/strong> mostra la lavorazione tecnica del cortometraggio di animazione &#8220;Ati alla scoperta di Veio&#8221;, creato nel VistLab di Cineca tra il 18 Marzo 2013 ed il 20 Ottobre 2014.<\/p>\n<p>A partire dai dati dei log di produzione \u00e8 stata creata questa rappresentazione animata:<br \/>\nle persone coinvolte sono identificate con il nome utente, le linee rappresentano le cartelle di sistema ed i pallini generati sono file, ogni modifica o creazione tramite Commit SVN dei files \u00e8 un fascio di luce.<\/p>\n<p>Notate i fantastici fiori fucsia che si aprono ad un certo punto sulla lavorazione delle <strong>trecce di Ati<\/strong>.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ZXbWor9zu0s?rel=0&amp;html5=1\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n<span style=\"font-size: xx-small;\">Se non vedete il filmato potete usare il seguente <a title=\"Infografica Ati alla scoperta di Veio\" href=\"https:\/\/youtu.be\/ZXbWor9zu0s\" target=\"_blank\" rel=\"noopener noreferrer\">link<\/a><\/span><\/p>\n<p>Questa \u00e8 la lavorazione nel dettaglio (10 minuti): <iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/-dnPdmU8y5Y?rel=0&amp;html5=1\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n<span style=\"font-size: xx-small;\">Se non vedete il filmato potete usare il seguente <a title=\"Infografica 10 minuti di Ati alla scoperta di Veio\" href=\"https:\/\/youtu.be\/-dnPdmU8y5Y\" target=\"_blank\" rel=\"noopener noreferrer\">link<\/a><\/span><\/p>\n<p>Simulazione creata con <a title=\"Gource\" href=\"https:\/\/code.google.com\/p\/gource\/\" target=\"_blank\" rel=\"noopener noreferrer\">Gource<\/a> a partire dai log SVN<\/p>\n<p>Impostazioni Gource:<br \/>\n1 giorno = 0.1 secondi<br \/>\nSkip immediato se non avviene nulla<br \/>\nNessun limite per numero di file visibili<br \/>\nNessuna scomparsa file<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che Ati fosse un fiore gi\u00e0 lo sapevamo; adesso, grazie all&#8217;infografica realizzata da Daniele, ne abbiamo la certezza. L&#8217;infografica mostra la lavorazione tecnica del cortometraggio di animazione &#8220;Ati alla scoperta di Veio&#8221;, creato nel VistLab di Cineca tra il 18 Marzo 2013 ed il 20 Ottobre 2014. A partire dai dati dei log di produzione [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2482,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15,3,4,8],"tags":[35,37,40,41,67,68,77,78,89,90,110,111],"class_list":["post-849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ati-alla-scoperta-di-veio","category-blender-modeling","category-dissemination","category-laboratorio","tag-ati","tag-blender-modeling","tag-capelli-di-ati","tag-capelli-in-blender","tag-gource","tag-hair-ati","tag-modellazione-ati","tag-modellazione-in-blender","tag-pipeline-3d-in-blender","tag-progettazione-generale-di-ati","tag-subversion","tag-svn"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/posts\/849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/comments?post=849"}],"version-history":[{"count":1,"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/posts\/849\/revisions"}],"predecessor-version":[{"id":3208,"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/posts\/849\/revisions\/3208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/media\/2482"}],"wp:attachment":[{"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/media?parent=849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/categories?post=849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitlab.cineca.it\/index.php\/wp-json\/wp\/v2\/tags?post=849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}